{"id":87,"date":"2021-07-12T01:57:13","date_gmt":"2021-07-11T23:57:13","guid":{"rendered":"https:\/\/workcontrol.net\/web\/?page_id=87"},"modified":"2021-07-12T01:57:14","modified_gmt":"2021-07-11T23:57:14","slug":"galeria-control-laboral","status":"publish","type":"page","link":"https:\/\/workcontrol.net\/web\/galeria-control-laboral\/","title":{"rendered":"Galer\u00eda Control Laboral"},"content":{"rendered":"\n<div class=\"wp-block-responsive-lightbox-gallery\"><div class=\"rl-gallery-container rl-loading rl-pagination-infinite\" id=\"rl-gallery-container-1\" data-gallery_id=\"89\"> <div class=\"rl-gallery rl-basicgrid-gallery \" id=\"rl-gallery-1\" data-gallery_no=\"1\"> <div class=\"rl-gallery-item\"><a href=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/login.png\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/login-240x145.png\" width=\"240\" height=\"145\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-caption\">control jornada laboral &#8211; login<\/span><\/span><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/principal.png\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/principal-240x145.png\" width=\"240\" height=\"145\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-caption\">principal<\/span><\/span><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/picking_manual.png\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/picking_manual-240x145.png\" width=\"240\" height=\"145\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-caption\">picking_manual<\/span><\/span><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/registros_usuario_2.png\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/registros_usuario_2-240x145.png\" width=\"240\" height=\"145\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-caption\">control jornada laboral &#8211; registros<\/span><\/span><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/listado_registros.png\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/listado_registros-240x145.png\" width=\"240\" height=\"145\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-caption\">listado_registros<\/span><\/span><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/registros_usuario_grafica_2.png\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/registros_usuario_grafica_2-240x145.png\" width=\"240\" height=\"145\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-caption\">registros_usuario_grafica_2<\/span><\/span><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/registros_usuario_grafica_1.png\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/registros_usuario_grafica_1-240x145.png\" width=\"240\" height=\"145\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-caption\">registros_usuario_grafica_1<\/span><\/span><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/menu.png\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/menu-240x145.png\" width=\"240\" height=\"145\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-caption\">menu<\/span><\/span><\/a><\/div><div class=\"rl-gallery-item\"><a href=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/listado_empresas.png\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/07\/listado_empresas-240x145.png\" width=\"240\" height=\"145\" \/><span class=\"rl-gallery-caption\"><span class=\"rl-gallery-item-caption\">listado_empresas<\/span><\/span><\/a><\/div> <\/div> <div class=\"rl-pagination rl-pagination-bottom\" data-button=\"automatically\"><\/div> <\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-87","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Galer\u00eda Control Laboral - Work Control<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/workcontrol.net\/web\/galeria-control-laboral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galer\u00eda Control Laboral - Work Control\" \/>\n<meta property=\"og:url\" content=\"https:\/\/workcontrol.net\/web\/galeria-control-laboral\/\" \/>\n<meta property=\"og:site_name\" content=\"Work Control\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-11T23:57:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/galeria-control-laboral\\\/\",\"url\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/galeria-control-laboral\\\/\",\"name\":\"Galer\u00eda Control Laboral - Work Control\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/#website\"},\"datePublished\":\"2021-07-11T23:57:13+00:00\",\"dateModified\":\"2021-07-11T23:57:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/galeria-control-laboral\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/workcontrol.net\\\/web\\\/galeria-control-laboral\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/galeria-control-laboral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galer\u00eda Control Laboral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/\",\"name\":\"Work Control\",\"description\":\"Control de jornada laboral\",\"publisher\":{\"@id\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/#organization\",\"name\":\"Work Control\",\"url\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-work_control_150x120.png\",\"contentUrl\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-work_control_150x120.png\",\"width\":240,\"height\":240,\"caption\":\"Work Control\"},\"image\":{\"@id\":\"https:\\\/\\\/workcontrol.net\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galer\u00eda Control Laboral - Work Control","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/workcontrol.net\/web\/galeria-control-laboral\/","og_locale":"es_ES","og_type":"article","og_title":"Galer\u00eda Control Laboral - Work Control","og_url":"https:\/\/workcontrol.net\/web\/galeria-control-laboral\/","og_site_name":"Work Control","article_modified_time":"2021-07-11T23:57:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/workcontrol.net\/web\/galeria-control-laboral\/","url":"https:\/\/workcontrol.net\/web\/galeria-control-laboral\/","name":"Galer\u00eda Control Laboral - Work Control","isPartOf":{"@id":"https:\/\/workcontrol.net\/web\/#website"},"datePublished":"2021-07-11T23:57:13+00:00","dateModified":"2021-07-11T23:57:14+00:00","breadcrumb":{"@id":"https:\/\/workcontrol.net\/web\/galeria-control-laboral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/workcontrol.net\/web\/galeria-control-laboral\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/workcontrol.net\/web\/galeria-control-laboral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/workcontrol.net\/web\/"},{"@type":"ListItem","position":2,"name":"Galer\u00eda Control Laboral"}]},{"@type":"WebSite","@id":"https:\/\/workcontrol.net\/web\/#website","url":"https:\/\/workcontrol.net\/web\/","name":"Work Control","description":"Control de jornada laboral","publisher":{"@id":"https:\/\/workcontrol.net\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/workcontrol.net\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/workcontrol.net\/web\/#organization","name":"Work Control","url":"https:\/\/workcontrol.net\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/workcontrol.net\/web\/#\/schema\/logo\/image\/","url":"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/06\/cropped-work_control_150x120.png","contentUrl":"https:\/\/workcontrol.net\/web\/wp-content\/uploads\/2021\/06\/cropped-work_control_150x120.png","width":240,"height":240,"caption":"Work Control"},"image":{"@id":"https:\/\/workcontrol.net\/web\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/workcontrol.net\/web\/wp-json\/wp\/v2\/pages\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/workcontrol.net\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/workcontrol.net\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/workcontrol.net\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/workcontrol.net\/web\/wp-json\/wp\/v2\/comments?post=87"}],"version-history":[{"count":1,"href":"https:\/\/workcontrol.net\/web\/wp-json\/wp\/v2\/pages\/87\/revisions"}],"predecessor-version":[{"id":90,"href":"https:\/\/workcontrol.net\/web\/wp-json\/wp\/v2\/pages\/87\/revisions\/90"}],"wp:attachment":[{"href":"https:\/\/workcontrol.net\/web\/wp-json\/wp\/v2\/media?parent=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}